{"id":2505,"date":"2018-09-21T12:52:09","date_gmt":"2018-09-21T15:52:09","guid":{"rendered":"https:\/\/chandlerorchards.com\/?page_id=2505"},"modified":"2019-01-28T16:04:48","modified_gmt":"2019-01-28T19:04:48","slug":"estudio-de-suelos","status":"publish","type":"page","link":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/","title":{"rendered":"Estudio de Suelos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2505\" class=\"elementor elementor-2505 elementor-2504 elementor-bc-flex-widget\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-f7af65d elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f7af65d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve-asymmetrical&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0ba3a0\" data-id=\"e0ba3a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10f9d22 elementor-widget elementor-widget-heading\" data-id=\"10f9d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Estudios de Suelo<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a55a71b elementor-widget elementor-widget-heading\" data-id=\"a55a71b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Resultado del estudio de suelos de Chandler Orchards<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e6c02a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e6c02a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b66aeee\" data-id=\"b66aeee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1fc7a9 elementor-widget elementor-widget-text-editor\" data-id=\"f1fc7a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A fines de 2009 encargamos un an\u00e1lisis de suelos para asegurar que nuestro campo fuera apto para el cultivo de nogales. M\u00e1s abajo ofrecemos un resumen del an\u00e1lisis, incluyendo los estudios de laboratorio de las pruebas realizadas en las porciones de muestra que se realizaron en nuestra propiedad. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b9a72e elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9b9a72e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-df68998\" data-id=\"df68998\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd241f1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bd241f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3.png\" class=\"attachment-full size-full wp-image-2618\" alt=\"\" srcset=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3.png 500w, https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3-150x150.png 150w, https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3-300x300.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Buen Drenaje<\/h5><p class=\"elementor-image-box-description\">El suelo es arenoso con buen drenaje<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-034bedd\" data-id=\"034bedd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a4cbe elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"51a4cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/4-1-1.png\" class=\"attachment-full size-full wp-image-2576\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">PH Neutral<\/h5><p class=\"elementor-image-box-description\">El pH var\u00eda entre 7.06 y 7.48, entre neutral y ligeramente alcalino<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7a4d8ab\" data-id=\"7a4d8ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b736b92 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b736b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/2-2-1.png\" class=\"attachment-full size-full wp-image-2572\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Sin l\u00edmites<\/h5><p class=\"elementor-image-box-description\">El suelo no tiene limitaciones para el cultivo.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-bf50cd0\" data-id=\"bf50cd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f980962 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f980962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/3-3-1.png\" class=\"attachment-full size-full wp-image-2574\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Apto para nueces<\/h5><p class=\"elementor-image-box-description\">Los cultivos recomendado son vi\u00f1edos \u00f3 \u00e1rboles frutales (tales como los nogales)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-677c4e7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"677c4e7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f852107\" data-id=\"f852107\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-378d518 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"378d518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEstudio completo de suelos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<p>Para m\u00e1s informaci\u00f3n, te invitamos a leer el estudio completo de suelos.<\/p>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bd395d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5bd395d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<article class=\"elementor-section elementor-top-section elementor-element elementor-element-2df6d6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2df6d6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-faa6bed\" data-id=\"faa6bed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1d83e9 elementor-widget elementor-widget-html\" data-id=\"e1d83e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p  style=\"   margin: 12px auto 6px auto;   font-family: Helvetica,Arial,Sans-serif;   font-style: normal;   font-variant: normal;   font-weight: normal;   font-size: 14px;   line-height: normal;   font-size-adjust: none;   font-stretch: normal;   -x-system-font: none;   display: block;\"   ><a title=\"View CARACTERI\u0301STICAS DEL SUELO EN CHANDLER ORCHARDS on Scribd\" href=\"https:\/\/www.scribd.com\/document\/388623758\/CARACTERI-STICAS-DEL-SUELO-EN-CHANDLER-ORCHARDS#from_embed\"  style=\"text-decoration: underline;\">CARACTERI\u0301STICAS DEL SUELO E...<\/a> by <a title=\"View 's profile on Scribd\" href=\"undefined#from_embed\"  style=\"text-decoration: underline;\"><\/a> on Scribd<\/p><iframe class=\"scribd_iframe_embed\" title=\"CARACTERI\u0301STICAS DEL SUELO EN CHANDLER ORCHARDS\" src=\"https:\/\/www.scribd.com\/embeds\/388623758\/content?start_page=1&view_mode=scroll&show_recommendations=true&access_key=key-WCdP4mWjDvmVYB0MGh07\" data-auto-height=\"true\" data-aspect-ratio=\"null\" scrolling=\"no\" width=\"100%\" height=\"600\" frameborder=\"0\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Estudios de Suelo Resultado del estudio de suelos de Chandler Orchards A fines de 2009 encargamos un an\u00e1lisis de suelos para asegurar que nuestro campo fuera apto para el cultivo de nogales. M\u00e1s abajo ofrecemos un resumen del an\u00e1lisis, incluyendo los estudios de laboratorio de las pruebas realizadas en las porciones de muestra que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[],"class_list":["post-2505","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio de Suelos &#8226; Chandler Orchards<\/title>\n<meta name=\"description\" content=\"A fines de 2009 encargamos un an\u00e1lisis de suelos para asegurar que nuestro campo fuera apto para el cultivo de nogales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio de Suelos\" \/>\n<meta property=\"og:description\" content=\"El suelo no tiene limitaciones para el cultivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/\" \/>\n<meta property=\"og:site_name\" content=\"Chandler Orchards\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chandlerorchards\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-28T19:04:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/agriculture-close-up-cultivation-169523-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Estudio de Suelos\" \/>\n<meta name=\"twitter:description\" content=\"El suelo no tiene limitaciones para el cultivo.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/agriculture-close-up-cultivation-169523-1-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/\",\"url\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/\",\"name\":\"Estudio de Suelos &#8226; Chandler Orchards\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chandlerorchards.com\\\/wp-content\\\/uploads\\\/1-3.png\",\"datePublished\":\"2018-09-21T15:52:09+00:00\",\"dateModified\":\"2019-01-28T19:04:48+00:00\",\"description\":\"A fines de 2009 encargamos un an\u00e1lisis de suelos para asegurar que nuestro campo fuera apto para el cultivo de nogales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chandlerorchards.com\\\/wp-content\\\/uploads\\\/1-3.png\",\"contentUrl\":\"https:\\\/\\\/chandlerorchards.com\\\/wp-content\\\/uploads\\\/1-3.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/estudio-de-suelos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chandlerorchards.com\\\/es\\\/inversion-en-nogales-en-mendoza-argentina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio de Suelos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/#website\",\"url\":\"https:\\\/\\\/chandlerorchards.com\\\/\",\"name\":\"Chandler Orchards\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chandlerorchards.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/#organization\",\"name\":\"Chandler Orchards\",\"url\":\"https:\\\/\\\/chandlerorchards.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chandlerorchards.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/chandler_orchards_360px_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/chandlerorchards.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/chandler_orchards_360px_logo-1.png\",\"width\":360,\"height\":360,\"caption\":\"Chandler Orchards\"},\"image\":{\"@id\":\"https:\\\/\\\/chandlerorchards.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chandlerorchards\\\/\",\"https:\\\/\\\/www.instagram.com\\\/chandlerorchards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChc9UYe8FHa6NY9oMxZd6JQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio de Suelos &#8226; Chandler Orchards","description":"A fines de 2009 encargamos un an\u00e1lisis de suelos para asegurar que nuestro campo fuera apto para el cultivo de nogales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio de Suelos","og_description":"El suelo no tiene limitaciones para el cultivo.","og_url":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/","og_site_name":"Chandler Orchards","article_publisher":"https:\/\/www.facebook.com\/chandlerorchards\/","article_modified_time":"2019-01-28T19:04:48+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/agriculture-close-up-cultivation-169523-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Estudio de Suelos","twitter_description":"El suelo no tiene limitaciones para el cultivo.","twitter_image":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/agriculture-close-up-cultivation-169523-1-1.jpg","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/","url":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/","name":"Estudio de Suelos &#8226; Chandler Orchards","isPartOf":{"@id":"https:\/\/chandlerorchards.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/#primaryimage"},"image":{"@id":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/#primaryimage"},"thumbnailUrl":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3.png","datePublished":"2018-09-21T15:52:09+00:00","dateModified":"2019-01-28T19:04:48+00:00","description":"A fines de 2009 encargamos un an\u00e1lisis de suelos para asegurar que nuestro campo fuera apto para el cultivo de nogales.","breadcrumb":{"@id":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/#primaryimage","url":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3.png","contentUrl":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/1-3.png"},{"@type":"BreadcrumbList","@id":"https:\/\/chandlerorchards.com\/es\/estudio-de-suelos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chandlerorchards.com\/es\/inversion-en-nogales-en-mendoza-argentina\/"},{"@type":"ListItem","position":2,"name":"Estudio de Suelos"}]},{"@type":"WebSite","@id":"https:\/\/chandlerorchards.com\/#website","url":"https:\/\/chandlerorchards.com\/","name":"Chandler Orchards","description":"","publisher":{"@id":"https:\/\/chandlerorchards.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chandlerorchards.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/chandlerorchards.com\/#organization","name":"Chandler Orchards","url":"https:\/\/chandlerorchards.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chandlerorchards.com\/#\/schema\/logo\/image\/","url":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/chandler_orchards_360px_logo-1.png","contentUrl":"https:\/\/chandlerorchards.com\/wp-content\/uploads\/2022\/06\/chandler_orchards_360px_logo-1.png","width":360,"height":360,"caption":"Chandler Orchards"},"image":{"@id":"https:\/\/chandlerorchards.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chandlerorchards\/","https:\/\/www.instagram.com\/chandlerorchards\/","https:\/\/www.youtube.com\/channel\/UChc9UYe8FHa6NY9oMxZd6JQ"]}]}},"_links":{"self":[{"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/pages\/2505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/comments?post=2505"}],"version-history":[{"count":9,"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/pages\/2505\/revisions"}],"predecessor-version":[{"id":5833,"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/pages\/2505\/revisions\/5833"}],"wp:attachment":[{"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/media?parent=2505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/categories?post=2505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chandlerorchards.com\/es\/wp-json\/wp\/v2\/tags?post=2505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}